{"id":11,"date":"2026-03-31T17:57:47","date_gmt":"2026-03-31T08:57:47","guid":{"rendered":"https:\/\/narauoichi.co.jp\/wordpress\/?page_id=11"},"modified":"2026-03-31T17:58:22","modified_gmt":"2026-03-31T08:58:22","slug":"home","status":"publish","type":"page","link":"https:\/\/narauoichi.co.jp\/recruit\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":1,"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":12,"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/11\/revisions\/12"}],"wp:attachment":[{"href":"https:\/\/narauoichi.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}